{"id":202,"date":"2024-06-12T11:14:47","date_gmt":"2024-06-12T09:14:47","guid":{"rendered":"https:\/\/humanmarketing.es\/?p=202"},"modified":"2024-11-20T12:20:45","modified_gmt":"2024-11-20T11:20:45","slug":"transformacion-digital","status":"publish","type":"post","link":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/","title":{"rendered":"El fracaso de la transformaci\u00f3n digital"},"content":{"rendered":"[et_pb_section admin_label=&#8221;section&#8221;]\n\t\t\t[et_pb_row admin_label=&#8221;row&#8221;]\n\t\t\t\t[et_pb_column type=&#8221;4_4&#8243;][et_pb_text admin_label=&#8221;Text&#8221;]\n<p>Voy a empezar por el final. La falta de liderazgo digital es una de las principales razones del fracaso, o la raz\u00f3n de que sea m\u00e1s lento de lo esperado.<br>Llevamos a\u00f1os hablando de transformaci\u00f3n digital. Hace unos a\u00f1os hac\u00eda referencia a la digitalizaci\u00f3n y aplicaci\u00f3n de nuevas tecnolog\u00edas en el \u00e1mbito empresarial. Hoy en d\u00eda, este concepto abarca tambi\u00e9n la transformaci\u00f3n de los modelos de negocios. En el 2022 IDC predec\u00eda \u2013acertadamente- que casi el 50% de los ingresos de las compa\u00f1\u00edas ser\u00edan generados por negocios digitales.<br>Durante este verano he tenido la oportunidad de debatir este tema con amigos y conocidos que trabajan en diferentes sectores como banca, seguros, medios, agencias, automoci\u00f3n, servicios entre otros. Todos ellos est\u00e1n inmersos en grandes cambios de procesos y de modelos de negocio.<br><br>La inversi\u00f3n en tecnolog\u00eda ya no es un freno. Nuevos modelos de IaaS, PaaS, SaaS nos ayudan a ser m\u00e1s eficientes que nunca en nuestras inversiones. Igualmente, la adopci\u00f3n de la tecnolog\u00eda cada vez resulta m\u00e1s sencilla y r\u00e1pida.<\/p>\n\n\n\n<p>En mi opini\u00f3n, hay 3 elementos que son fundamentales para conseguir el \u00e9xito:<br>1- No se trata de construir la visi\u00f3n de compa\u00f1\u00eda, sino de transmitirla con credibilidad. Hace poco hice un curso en Stanford sobre \u201cla neurociencia aplicada al liderazgo\u201d. Comparto uno de los aprendizajes que m\u00e1s me gust\u00f3. En muchas ocasiones con encontramos con varias opciones en la toma de decisiones. Despu\u00e9s de un an\u00e1lisis para determinar pros y contras (hay mucha metodolog\u00eda detr\u00e1s que no entraremos hoy en esto), muchas veces terminamos en dos o m\u00e1s opciones con ponderaci\u00f3n semejante. \u00bfC\u00f3mo decidir cu\u00e1l es la opci\u00f3n correcta? Hay muchas variables externas y cambiantes que no podemos controlar, por lo tanto nunca sabremos cu\u00e1l es la opci\u00f3n m\u00e1s acertada. La Neurociencia ha demostrado que debemos elegir la opci\u00f3n que m\u00e1s nos ilusione ya que cuando bajes a los equipos la estrategia, lo har\u00e1s con mayor credibilidad y conseguir\u00e1s empleados m\u00e1s comprometidos.<br>2- Los l\u00edderes digitales tienen menos miedo al error \u2013aprender de los errores y no volverlos a cometer es parte del proceso-, invertir en innovaci\u00f3n, a testar nuevos modelos y procesos, una mayor resiliencia. No cuentan con creencias basadas en el modelo tradicional, y el \u201clegacy\u201d del \u201csiempre se ha hecho as\u00ed\u201d.<br>3- Procesos y metodolog\u00edas agiles y con equipos multidisciplinares. No se trata de aplicar metodolog\u00edas \u00e1giles, de nada sirve si la organizaci\u00f3n y sus procesos o tomas de decisiones no son agiles. Aqu\u00ed entran temas como la definici\u00f3n de objetivos transversales, pero sobre todo delegar la toma de decisiones y empoderar a segundas capas de management, e involucrando a los empleados.<br><br>Para tener \u00e9xito en la adopci\u00f3n de nuevos modelos de negocio, se debe abordar un nuevo liderazgo digital, manteniendo un enfoque constante en la mejora continua y la adaptaci\u00f3n a un entorno empresarial en constante evoluci\u00f3n.<\/p>\n[\/et_pb_text][\/et_pb_column]\n\t\t\t[\/et_pb_row]\n\t\t[\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>Voy a empezar por el final. La falta de liderazgo digital es una de las principales razones del fracaso, o la raz\u00f3n de que sea m\u00e1s lento de lo esperado.Llevamos a\u00f1os hablando de transformaci\u00f3n digital. Hace unos a\u00f1os hac\u00eda referencia a la digitalizaci\u00f3n y aplicaci\u00f3n de nuevas tecnolog\u00edas en el \u00e1mbito empresarial. Hoy en d\u00eda, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":305,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:paragraph -->\n<p>Voy a empezar por el final. La falta de liderazgo digital es una de las principales razones del fracaso, o la raz\u00f3n de que sea m\u00e1s lento de lo esperado.<br>Llevamos a\u00f1os hablando de transformaci\u00f3n digital. Hace unos a\u00f1os hac\u00eda referencia a la digitalizaci\u00f3n y aplicaci\u00f3n de nuevas tecnolog\u00edas en el \u00e1mbito empresarial. Hoy en d\u00eda, este concepto abarca tambi\u00e9n la transformaci\u00f3n de los modelos de negocios. En el 2022 IDC predec\u00eda \u2013acertadamente- que casi el 50% de los ingresos de las compa\u00f1\u00edas ser\u00edan generados por negocios digitales.<br>Durante este verano he tenido la oportunidad de debatir este tema con amigos y conocidos que trabajan en diferentes sectores como banca, seguros, medios, agencias, automoci\u00f3n, servicios entre otros. Todos ellos est\u00e1n inmersos en grandes cambios de procesos y de modelos de negocio.<br><br>La inversi\u00f3n en tecnolog\u00eda ya no es un freno. Nuevos modelos de IaaS, PaaS, SaaS nos ayudan a ser m\u00e1s eficientes que nunca en nuestras inversiones. Igualmente, la adopci\u00f3n de la tecnolog\u00eda cada vez resulta m\u00e1s sencilla y r\u00e1pida.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>En mi opini\u00f3n, hay 3 elementos que son fundamentales para conseguir el \u00e9xito:<br>1- No se trata de construir la visi\u00f3n de compa\u00f1\u00eda, sino de transmitirla con credibilidad. Hace poco hice un curso en Stanford sobre \u201cla neurociencia aplicada al liderazgo\u201d. Comparto uno de los aprendizajes que m\u00e1s me gust\u00f3. En muchas ocasiones con encontramos con varias opciones en la toma de decisiones. Despu\u00e9s de un an\u00e1lisis para determinar pros y contras (hay mucha metodolog\u00eda detr\u00e1s que no entraremos hoy en esto), muchas veces terminamos en dos o m\u00e1s opciones con ponderaci\u00f3n semejante. \u00bfC\u00f3mo decidir cu\u00e1l es la opci\u00f3n correcta? Hay muchas variables externas y cambiantes que no podemos controlar, por lo tanto nunca sabremos cu\u00e1l es la opci\u00f3n m\u00e1s acertada. La Neurociencia ha demostrado que debemos elegir la opci\u00f3n que m\u00e1s nos ilusione ya que cuando bajes a los equipos la estrategia, lo har\u00e1s con mayor credibilidad y conseguir\u00e1s empleados m\u00e1s comprometidos.<br>2- Los l\u00edderes digitales tienen menos miedo al error \u2013aprender de los errores y no volverlos a cometer es parte del proceso-, invertir en innovaci\u00f3n, a testar nuevos modelos y procesos, una mayor resiliencia. No cuentan con creencias basadas en el modelo tradicional, y el \u201clegacy\u201d del \u201csiempre se ha hecho as\u00ed\u201d.<br>3- Procesos y metodolog\u00edas agiles y con equipos multidisciplinares. No se trata de aplicar metodolog\u00edas \u00e1giles, de nada sirve si la organizaci\u00f3n y sus procesos o tomas de decisiones no son agiles. Aqu\u00ed entran temas como la definici\u00f3n de objetivos transversales, pero sobre todo delegar la toma de decisiones y empoderar a segundas capas de management, e involucrando a los empleados.<br><br>Para tener \u00e9xito en la adopci\u00f3n de nuevos modelos de negocio, se debe abordar un nuevo liderazgo digital, manteniendo un enfoque constante en la mejora continua y la adaptaci\u00f3n a un entorno empresarial en constante evoluci\u00f3n.<\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[10,13,12,11,14],"class_list":["post-202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-blog","tag-digital","tag-human","tag-marketing","tag-transformacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El fracaso de la transformaci\u00f3n digital - Human Marketing<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El fracaso de la transformaci\u00f3n digital - Human Marketing\" \/>\n<meta property=\"og:description\" content=\"Voy a empezar por el final. La falta de liderazgo digital es una de las principales razones del fracaso, o la raz\u00f3n de que sea m\u00e1s lento de lo esperado.Llevamos a\u00f1os hablando de transformaci\u00f3n digital. Hace unos a\u00f1os hac\u00eda referencia a la digitalizaci\u00f3n y aplicaci\u00f3n de nuevas tecnolog\u00edas en el \u00e1mbito empresarial. Hoy en d\u00eda, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/\" \/>\n<meta property=\"og:site_name\" content=\"Human Marketing\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-12T09:14:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-20T11:20:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/humanmarketing.es\/wp-content\/uploads\/2024\/06\/Transformacion-digital.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"humanmarketing.es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"humanmarketing.es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/\"},\"author\":{\"name\":\"humanmarketing.es\",\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/#\\\/schema\\\/person\\\/9f06cb9d4e4fcadd577eec9475e4d653\"},\"headline\":\"El fracaso de la transformaci\u00f3n digital\",\"datePublished\":\"2024-06-12T09:14:47+00:00\",\"dateModified\":\"2024-11-20T11:20:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/\"},\"wordCount\":564,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/humanmarketing.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Transformacion-digital.jpeg\",\"keywords\":[\"blog\",\"digital\",\"human\",\"marketing\",\"transformaci\u00f3n\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/\",\"url\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/\",\"name\":\"El fracaso de la transformaci\u00f3n digital - Human Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/humanmarketing.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Transformacion-digital.jpeg\",\"datePublished\":\"2024-06-12T09:14:47+00:00\",\"dateModified\":\"2024-11-20T11:20:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/#\\\/schema\\\/person\\\/9f06cb9d4e4fcadd577eec9475e4d653\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/#primaryimage\",\"url\":\"https:\\\/\\\/humanmarketing.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Transformacion-digital.jpeg\",\"contentUrl\":\"https:\\\/\\\/humanmarketing.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Transformacion-digital.jpeg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/2024\\\/06\\\/12\\\/transformacion-digital\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/humanmarketing.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El fracaso de la transformaci\u00f3n digital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/#website\",\"url\":\"https:\\\/\\\/humanmarketing.es\\\/\",\"name\":\"Human Marketing\",\"description\":\"Creando conexiones Escucha, analiza, act\u00faa.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/humanmarketing.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/humanmarketing.es\\\/#\\\/schema\\\/person\\\/9f06cb9d4e4fcadd577eec9475e4d653\",\"name\":\"humanmarketing.es\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8887d459303d772ec30d98f57c1eda11c549c8632f26f917887f2bc1eff499ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8887d459303d772ec30d98f57c1eda11c549c8632f26f917887f2bc1eff499ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8887d459303d772ec30d98f57c1eda11c549c8632f26f917887f2bc1eff499ef?s=96&d=mm&r=g\",\"caption\":\"humanmarketing.es\"},\"sameAs\":[\"https:\\\/\\\/humanmarketing.es\"],\"url\":\"https:\\\/\\\/humanmarketing.es\\\/index.php\\\/author\\\/plantilla-the-one-to-test-es\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El fracaso de la transformaci\u00f3n digital - Human Marketing","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/","og_locale":"en_US","og_type":"article","og_title":"El fracaso de la transformaci\u00f3n digital - Human Marketing","og_description":"Voy a empezar por el final. La falta de liderazgo digital es una de las principales razones del fracaso, o la raz\u00f3n de que sea m\u00e1s lento de lo esperado.Llevamos a\u00f1os hablando de transformaci\u00f3n digital. Hace unos a\u00f1os hac\u00eda referencia a la digitalizaci\u00f3n y aplicaci\u00f3n de nuevas tecnolog\u00edas en el \u00e1mbito empresarial. Hoy en d\u00eda, [&hellip;]","og_url":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/","og_site_name":"Human Marketing","article_published_time":"2024-06-12T09:14:47+00:00","article_modified_time":"2024-11-20T11:20:45+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/humanmarketing.es\/wp-content\/uploads\/2024\/06\/Transformacion-digital.jpeg","type":"image\/jpeg"}],"author":"humanmarketing.es","twitter_card":"summary_large_image","twitter_misc":{"Written by":"humanmarketing.es","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/#article","isPartOf":{"@id":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/"},"author":{"name":"humanmarketing.es","@id":"https:\/\/humanmarketing.es\/#\/schema\/person\/9f06cb9d4e4fcadd577eec9475e4d653"},"headline":"El fracaso de la transformaci\u00f3n digital","datePublished":"2024-06-12T09:14:47+00:00","dateModified":"2024-11-20T11:20:45+00:00","mainEntityOfPage":{"@id":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/"},"wordCount":564,"commentCount":0,"image":{"@id":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/humanmarketing.es\/wp-content\/uploads\/2024\/06\/Transformacion-digital.jpeg","keywords":["blog","digital","human","marketing","transformaci\u00f3n"],"articleSection":["Blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/","url":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/","name":"El fracaso de la transformaci\u00f3n digital - Human Marketing","isPartOf":{"@id":"https:\/\/humanmarketing.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/#primaryimage"},"image":{"@id":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/#primaryimage"},"thumbnailUrl":"https:\/\/humanmarketing.es\/wp-content\/uploads\/2024\/06\/Transformacion-digital.jpeg","datePublished":"2024-06-12T09:14:47+00:00","dateModified":"2024-11-20T11:20:45+00:00","author":{"@id":"https:\/\/humanmarketing.es\/#\/schema\/person\/9f06cb9d4e4fcadd577eec9475e4d653"},"breadcrumb":{"@id":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/#primaryimage","url":"https:\/\/humanmarketing.es\/wp-content\/uploads\/2024\/06\/Transformacion-digital.jpeg","contentUrl":"https:\/\/humanmarketing.es\/wp-content\/uploads\/2024\/06\/Transformacion-digital.jpeg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/humanmarketing.es\/index.php\/2024\/06\/12\/transformacion-digital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/humanmarketing.es\/"},{"@type":"ListItem","position":2,"name":"El fracaso de la transformaci\u00f3n digital"}]},{"@type":"WebSite","@id":"https:\/\/humanmarketing.es\/#website","url":"https:\/\/humanmarketing.es\/","name":"Human Marketing","description":"Creando conexiones Escucha, analiza, act\u00faa.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/humanmarketing.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/humanmarketing.es\/#\/schema\/person\/9f06cb9d4e4fcadd577eec9475e4d653","name":"humanmarketing.es","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8887d459303d772ec30d98f57c1eda11c549c8632f26f917887f2bc1eff499ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8887d459303d772ec30d98f57c1eda11c549c8632f26f917887f2bc1eff499ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8887d459303d772ec30d98f57c1eda11c549c8632f26f917887f2bc1eff499ef?s=96&d=mm&r=g","caption":"humanmarketing.es"},"sameAs":["https:\/\/humanmarketing.es"],"url":"https:\/\/humanmarketing.es\/index.php\/author\/plantilla-the-one-to-test-es\/"}]}},"_links":{"self":[{"href":"https:\/\/humanmarketing.es\/index.php\/wp-json\/wp\/v2\/posts\/202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/humanmarketing.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/humanmarketing.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/humanmarketing.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/humanmarketing.es\/index.php\/wp-json\/wp\/v2\/comments?post=202"}],"version-history":[{"count":5,"href":"https:\/\/humanmarketing.es\/index.php\/wp-json\/wp\/v2\/posts\/202\/revisions"}],"predecessor-version":[{"id":423,"href":"https:\/\/humanmarketing.es\/index.php\/wp-json\/wp\/v2\/posts\/202\/revisions\/423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/humanmarketing.es\/index.php\/wp-json\/wp\/v2\/media\/305"}],"wp:attachment":[{"href":"https:\/\/humanmarketing.es\/index.php\/wp-json\/wp\/v2\/media?parent=202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/humanmarketing.es\/index.php\/wp-json\/wp\/v2\/categories?post=202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/humanmarketing.es\/index.php\/wp-json\/wp\/v2\/tags?post=202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}